{"id":4641,"count":1,"description":"","link":"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/","name":"Sunscreen","slug":"sunscreen","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Sunscreen - Esalab<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Sunscreen - Esalab\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/\" \/>\n<meta property=\"og:site_name\" content=\"Esalab\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/\",\"url\":\"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/\",\"name\":\"Arquivo de Sunscreen - Esalab\",\"isPartOf\":{\"@id\":\"https:\/\/www.esalab.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.esalab.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sunscreen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.esalab.com.br\/blog\/#website\",\"url\":\"https:\/\/www.esalab.com.br\/blog\/\",\"name\":\"Esalab\",\"description\":\"Blog\",\"publisher\":{\"@id\":\"https:\/\/www.esalab.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.esalab.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.esalab.com.br\/blog\/#organization\",\"name\":\"Esalab\",\"url\":\"https:\/\/www.esalab.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.esalab.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.esalab.com.br\/blog\/wp-content\/uploads\/2022\/06\/esalab-logo.png\",\"contentUrl\":\"https:\/\/www.esalab.com.br\/blog\/wp-content\/uploads\/2022\/06\/esalab-logo.png\",\"width\":250,\"height\":44,\"caption\":\"Esalab\"},\"image\":{\"@id\":\"https:\/\/www.esalab.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Sunscreen - Esalab","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Sunscreen - Esalab","og_url":"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/","og_site_name":"Esalab","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/","url":"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/","name":"Arquivo de Sunscreen - Esalab","isPartOf":{"@id":"https:\/\/www.esalab.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.esalab.com.br\/blog\/category\/sunscreen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.esalab.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Sunscreen"}]},{"@type":"WebSite","@id":"https:\/\/www.esalab.com.br\/blog\/#website","url":"https:\/\/www.esalab.com.br\/blog\/","name":"Esalab","description":"Blog","publisher":{"@id":"https:\/\/www.esalab.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.esalab.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.esalab.com.br\/blog\/#organization","name":"Esalab","url":"https:\/\/www.esalab.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.esalab.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.esalab.com.br\/blog\/wp-content\/uploads\/2022\/06\/esalab-logo.png","contentUrl":"https:\/\/www.esalab.com.br\/blog\/wp-content\/uploads\/2022\/06\/esalab-logo.png","width":250,"height":44,"caption":"Esalab"},"image":{"@id":"https:\/\/www.esalab.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.esalab.com.br\/blog\/wp-json\/wp\/v2\/categories\/4641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esalab.com.br\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.esalab.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.esalab.com.br\/blog\/wp-json\/wp\/v2\/posts?categories=4641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}